{"id":1495,"date":"2026-03-26T09:50:00","date_gmt":"2026-03-26T09:50:00","guid":{"rendered":"https:\/\/portugal.wordcamp.org\/2026\/?p=1495"},"modified":"2026-03-26T09:10:14","modified_gmt":"2026-03-26T09:10:14","slug":"restam-apenas-3-vagas-de-patrocinio-para-o-wordcamp-portugal","status":"publish","type":"post","link":"https:\/\/portugal.wordcamp.org\/2026\/restam-apenas-3-vagas-de-patrocinio-para-o-wordcamp-portugal\/","title":{"rendered":"Restam apenas 3 vagas de patroc\u00ednio para o WordCamp Portugal!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Enquanto nos preparamos para um evento inesquec\u00edvel no Porto, temos uma atualiza\u00e7\u00e3o r\u00e1pida: os nossos pacotes de patroc\u00ednio est\u00e3o quase esgotados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se queres colocar a tua marca perante centenas de profissionais de WordPress, bloggers e donos de neg\u00f3cio, esta \u00e9 a tua \u00faltima oportunidade de te juntares a n\u00f3s como parceiro oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temos apenas tr\u00eas vagas dispon\u00edveis:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Platina (restam 2 vagas)<\/strong><br>Este \u00e9 o nosso n\u00edvel de patroc\u00ednio mais prestigiado ainda dispon\u00edvel.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Destaque de Marca: Log\u00f3tipo em destaque no site e um artigo de agradecimento dedicado.<\/li>\n\n\n\n<li>Presen\u00e7a: Um espa\u00e7o de 2&#215;2 metros no hall principal para interagir com os participantes.<\/li>\n\n\n\n<li>Tempo de Palco: A tua marca poder\u00e1 anunciar o vencedor de um passatempo no palco principal.<\/li>\n\n\n\n<li>Benef\u00edcios: 3 Bilhetes para o evento + 3 convites para o jantar.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prata (apenas 1 vaga restante!)<\/strong><br>Perfeito para ag\u00eancias de menor dimens\u00e3o ou criadores de produtos que queiram apoiar a comunidade.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reconhecimento: Log\u00f3tipo de tamanho m\u00e9dio no site e inclus\u00e3o num artigo de agradecimento em grupo.<\/li>\n\n\n\n<li>Benef\u00edcios: 1 Bilhete para o evento + 1 convite para o jantar.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Visita a nossa <strong><a href=\"https:\/\/portugal.wordcamp.org\/2026\/chamada-a-patrocinadores\/\">P\u00e1gina de Patroc\u00ednios<\/a><\/strong> para consultar todos os detalhes e garante o teu lugar hoje mesmo.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-35f06ea7 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/portugal.wordcamp.org\/2026\/chamada-a-patrocinadores\/\"><strong>Quero patrocinar o WordCamp Portugal 2026<\/strong><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto nos preparamos para um evento inesquec\u00edvel no Porto, temos uma atualiza\u00e7\u00e3o r\u00e1pida: os nossos pacotes de patroc\u00ednio est\u00e3o quase esgotados. Se queres colocar a tua marca perante centenas de profissionais de WordPress, bloggers e donos de neg\u00f3cio, esta \u00e9 a tua \u00faltima oportunidade de te juntares a n\u00f3s como parceiro oficial. Temos apenas tr\u00eas [&hellip;]<\/p>\n","protected":false},"author":18051413,"featured_media":718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_nakedcatplugins_page_lang":"","_nakedcatplugins_page_dir":"ltr","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novidades"],"jetpack_featured_media_url":"https:\/\/portugal.wordcamp.org\/2026\/files\/2026\/01\/WCPT2026-Call-Sponsors_1200x630-PT.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/posts\/1495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/users\/18051413"}],"replies":[{"embeddable":true,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":1,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"predecessor-version":[{"id":1496,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/posts\/1495\/revisions\/1496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/media\/718"}],"wp:attachment":[{"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portugal.wordcamp.org\/2026\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}